{"id":10760,"date":"2023-09-11T13:46:58","date_gmt":"2023-09-11T13:46:58","guid":{"rendered":"https:\/\/arklam.com\/productos\/patagonia-gold-polished-bl-6-mm\/"},"modified":"2024-09-25T11:17:13","modified_gmt":"2024-09-25T10:17:13","slug":"patagonia-gold-polished-bl-6-mm","status":"publish","type":"producto","link":"https:\/\/arklam.com\/fr\/produits\/patagonia-gold-polished-bl-6-mm\/","title":{"rendered":"Patagonia Gold Polished BL 6 mm"},"content":{"rendered":"","protected":false},"featured_media":10754,"parent":0,"menu_order":95,"template":"","class_list":["post-10760","producto","type-producto","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Patagonia Gold Polished BL 6 mm - Arklam<\/title>\n<meta name=\"description\" content=\"Este m\u00e1rmol original de Italia presenta una gr\u00e1fica llena de matices en la que se entrelazan vetas doradas, grises y negras.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arklam.com\/fr\/produits\/patagonia-gold-polished-bl-6-mm\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Patagonia Gold Polished BL 6 mm - Arklam\" \/>\n<meta property=\"og:description\" content=\"Este m\u00e1rmol original de Italia presenta una gr\u00e1fica llena de matices en la que se entrelazan vetas doradas, grises y negras.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arklam.com\/fr\/produits\/patagonia-gold-polished-bl-6-mm\/\" \/>\n<meta property=\"og:site_name\" content=\"Arklam\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-25T10:17:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arklam.com\/wp-content\/uploads\/2023\/09\/Amb-Patagonia-Gold-Tienda-1200x3000-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1700\" \/>\n\t<meta property=\"og:image:height\" content=\"1190\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arklam.com\\\/fr\\\/produits\\\/patagonia-gold-polished-bl-6-mm\\\/\",\"url\":\"https:\\\/\\\/arklam.com\\\/fr\\\/produits\\\/patagonia-gold-polished-bl-6-mm\\\/\",\"name\":\"Patagonia Gold Polished BL 6 mm - Arklam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arklam.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arklam.com\\\/fr\\\/produits\\\/patagonia-gold-polished-bl-6-mm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arklam.com\\\/fr\\\/produits\\\/patagonia-gold-polished-bl-6-mm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arklam.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Amb-Patagonia-Gold-Tienda-1200x3000-1.jpg\",\"datePublished\":\"2023-09-11T13:46:58+00:00\",\"dateModified\":\"2024-09-25T10:17:13+00:00\",\"description\":\"Este m\u00e1rmol original de Italia presenta una gr\u00e1fica llena de matices en la que se entrelazan vetas doradas, grises y negras.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arklam.com\\\/fr\\\/produits\\\/patagonia-gold-polished-bl-6-mm\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arklam.com\\\/fr\\\/produits\\\/patagonia-gold-polished-bl-6-mm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/arklam.com\\\/fr\\\/produits\\\/patagonia-gold-polished-bl-6-mm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arklam.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Amb-Patagonia-Gold-Tienda-1200x3000-1.jpg\",\"contentUrl\":\"https:\\\/\\\/arklam.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Amb-Patagonia-Gold-Tienda-1200x3000-1.jpg\",\"width\":1700,\"height\":1190},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arklam.com\\\/fr\\\/produits\\\/patagonia-gold-polished-bl-6-mm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/arklam.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Patagonia Gold Polished BL 6 mm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arklam.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/arklam.com\\\/fr\\\/\",\"name\":\"Arklam\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arklam.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Patagonia Gold Polished BL 6 mm - Arklam","description":"Este m\u00e1rmol original de Italia presenta una gr\u00e1fica llena de matices en la que se entrelazan vetas doradas, grises y negras.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arklam.com\/fr\/produits\/patagonia-gold-polished-bl-6-mm\/","og_locale":"fr_FR","og_type":"article","og_title":"Patagonia Gold Polished BL 6 mm - Arklam","og_description":"Este m\u00e1rmol original de Italia presenta una gr\u00e1fica llena de matices en la que se entrelazan vetas doradas, grises y negras.","og_url":"https:\/\/arklam.com\/fr\/produits\/patagonia-gold-polished-bl-6-mm\/","og_site_name":"Arklam","article_modified_time":"2024-09-25T10:17:13+00:00","og_image":[{"width":1700,"height":1190,"url":"https:\/\/arklam.com\/wp-content\/uploads\/2023\/09\/Amb-Patagonia-Gold-Tienda-1200x3000-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/arklam.com\/fr\/produits\/patagonia-gold-polished-bl-6-mm\/","url":"https:\/\/arklam.com\/fr\/produits\/patagonia-gold-polished-bl-6-mm\/","name":"Patagonia Gold Polished BL 6 mm - Arklam","isPartOf":{"@id":"https:\/\/arklam.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arklam.com\/fr\/produits\/patagonia-gold-polished-bl-6-mm\/#primaryimage"},"image":{"@id":"https:\/\/arklam.com\/fr\/produits\/patagonia-gold-polished-bl-6-mm\/#primaryimage"},"thumbnailUrl":"https:\/\/arklam.com\/wp-content\/uploads\/2023\/09\/Amb-Patagonia-Gold-Tienda-1200x3000-1.jpg","datePublished":"2023-09-11T13:46:58+00:00","dateModified":"2024-09-25T10:17:13+00:00","description":"Este m\u00e1rmol original de Italia presenta una gr\u00e1fica llena de matices en la que se entrelazan vetas doradas, grises y negras.","breadcrumb":{"@id":"https:\/\/arklam.com\/fr\/produits\/patagonia-gold-polished-bl-6-mm\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arklam.com\/fr\/produits\/patagonia-gold-polished-bl-6-mm\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/arklam.com\/fr\/produits\/patagonia-gold-polished-bl-6-mm\/#primaryimage","url":"https:\/\/arklam.com\/wp-content\/uploads\/2023\/09\/Amb-Patagonia-Gold-Tienda-1200x3000-1.jpg","contentUrl":"https:\/\/arklam.com\/wp-content\/uploads\/2023\/09\/Amb-Patagonia-Gold-Tienda-1200x3000-1.jpg","width":1700,"height":1190},{"@type":"BreadcrumbList","@id":"https:\/\/arklam.com\/fr\/produits\/patagonia-gold-polished-bl-6-mm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/arklam.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Patagonia Gold Polished BL 6 mm"}]},{"@type":"WebSite","@id":"https:\/\/arklam.com\/fr\/#website","url":"https:\/\/arklam.com\/fr\/","name":"Arklam","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arklam.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/arklam.com\/fr\/wp-json\/wp\/v2\/producto\/10760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arklam.com\/fr\/wp-json\/wp\/v2\/producto"}],"about":[{"href":"https:\/\/arklam.com\/fr\/wp-json\/wp\/v2\/types\/producto"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arklam.com\/fr\/wp-json\/wp\/v2\/media\/10754"}],"wp:attachment":[{"href":"https:\/\/arklam.com\/fr\/wp-json\/wp\/v2\/media?parent=10760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}