{"id":12802,"date":"2025-07-14T12:50:15","date_gmt":"2025-07-14T11:50:15","guid":{"rendered":"https:\/\/arklam.com\/productos\/onice-black-polished-6-mm-2\/"},"modified":"2025-08-01T15:32:44","modified_gmt":"2025-08-01T14:32:44","slug":"onice-black-polished-6-mm","status":"publish","type":"producto","link":"https:\/\/arklam.com\/pl\/productos\/onice-black-polished-6-mm\/","title":{"rendered":"Onice Black Polished 6 mm"},"content":{"rendered":"","protected":false},"featured_media":9135,"parent":0,"menu_order":20,"template":"","class_list":["post-12802","producto","type-producto","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Onice Black Polished 6 mm - Arklam<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arklam.com\/pl\/productos\/onice-black-polished-6-mm\/\" \/>\n<meta property=\"og:locale\" content=\"pl_PL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Onice Black Polished 6 mm - Arklam\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arklam.com\/pl\/productos\/onice-black-polished-6-mm\/\" \/>\n<meta property=\"og:site_name\" content=\"Arklam\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-01T14:32:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arklam.com\/wp-content\/uploads\/2023\/02\/Amb-Onice-Black-Polished-1200x3000-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1700\" \/>\n\t<meta property=\"og:image:height\" content=\"1190\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arklam.com\\\/pl\\\/productos\\\/onice-black-polished-6-mm\\\/\",\"url\":\"https:\\\/\\\/arklam.com\\\/pl\\\/productos\\\/onice-black-polished-6-mm\\\/\",\"name\":\"Onice Black Polished 6 mm - Arklam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arklam.com\\\/pl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arklam.com\\\/pl\\\/productos\\\/onice-black-polished-6-mm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arklam.com\\\/pl\\\/productos\\\/onice-black-polished-6-mm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arklam.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Amb-Onice-Black-Polished-1200x3000-1.jpg\",\"datePublished\":\"2025-07-14T11:50:15+00:00\",\"dateModified\":\"2025-08-01T14:32:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arklam.com\\\/pl\\\/productos\\\/onice-black-polished-6-mm\\\/#breadcrumb\"},\"inLanguage\":\"pl-PL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arklam.com\\\/pl\\\/productos\\\/onice-black-polished-6-mm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pl-PL\",\"@id\":\"https:\\\/\\\/arklam.com\\\/pl\\\/productos\\\/onice-black-polished-6-mm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arklam.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Amb-Onice-Black-Polished-1200x3000-1.jpg\",\"contentUrl\":\"https:\\\/\\\/arklam.com\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Amb-Onice-Black-Polished-1200x3000-1.jpg\",\"width\":1700,\"height\":1190},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arklam.com\\\/pl\\\/productos\\\/onice-black-polished-6-mm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/arklam.com\\\/pl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Onice Black Polished 6 mm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arklam.com\\\/pl\\\/#website\",\"url\":\"https:\\\/\\\/arklam.com\\\/pl\\\/\",\"name\":\"Arklam\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arklam.com\\\/pl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pl-PL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Onice Black Polished 6 mm - Arklam","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arklam.com\/pl\/productos\/onice-black-polished-6-mm\/","og_locale":"pl_PL","og_type":"article","og_title":"Onice Black Polished 6 mm - Arklam","og_url":"https:\/\/arklam.com\/pl\/productos\/onice-black-polished-6-mm\/","og_site_name":"Arklam","article_modified_time":"2025-08-01T14:32:44+00:00","og_image":[{"width":1700,"height":1190,"url":"https:\/\/arklam.com\/wp-content\/uploads\/2023\/02\/Amb-Onice-Black-Polished-1200x3000-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/arklam.com\/pl\/productos\/onice-black-polished-6-mm\/","url":"https:\/\/arklam.com\/pl\/productos\/onice-black-polished-6-mm\/","name":"Onice Black Polished 6 mm - Arklam","isPartOf":{"@id":"https:\/\/arklam.com\/pl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arklam.com\/pl\/productos\/onice-black-polished-6-mm\/#primaryimage"},"image":{"@id":"https:\/\/arklam.com\/pl\/productos\/onice-black-polished-6-mm\/#primaryimage"},"thumbnailUrl":"https:\/\/arklam.com\/wp-content\/uploads\/2023\/02\/Amb-Onice-Black-Polished-1200x3000-1.jpg","datePublished":"2025-07-14T11:50:15+00:00","dateModified":"2025-08-01T14:32:44+00:00","breadcrumb":{"@id":"https:\/\/arklam.com\/pl\/productos\/onice-black-polished-6-mm\/#breadcrumb"},"inLanguage":"pl-PL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arklam.com\/pl\/productos\/onice-black-polished-6-mm\/"]}]},{"@type":"ImageObject","inLanguage":"pl-PL","@id":"https:\/\/arklam.com\/pl\/productos\/onice-black-polished-6-mm\/#primaryimage","url":"https:\/\/arklam.com\/wp-content\/uploads\/2023\/02\/Amb-Onice-Black-Polished-1200x3000-1.jpg","contentUrl":"https:\/\/arklam.com\/wp-content\/uploads\/2023\/02\/Amb-Onice-Black-Polished-1200x3000-1.jpg","width":1700,"height":1190},{"@type":"BreadcrumbList","@id":"https:\/\/arklam.com\/pl\/productos\/onice-black-polished-6-mm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/arklam.com\/pl\/"},{"@type":"ListItem","position":2,"name":"Onice Black Polished 6 mm"}]},{"@type":"WebSite","@id":"https:\/\/arklam.com\/pl\/#website","url":"https:\/\/arklam.com\/pl\/","name":"Arklam","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arklam.com\/pl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pl-PL"}]}},"_links":{"self":[{"href":"https:\/\/arklam.com\/pl\/wp-json\/wp\/v2\/producto\/12802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arklam.com\/pl\/wp-json\/wp\/v2\/producto"}],"about":[{"href":"https:\/\/arklam.com\/pl\/wp-json\/wp\/v2\/types\/producto"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arklam.com\/pl\/wp-json\/wp\/v2\/media\/9135"}],"wp:attachment":[{"href":"https:\/\/arklam.com\/pl\/wp-json\/wp\/v2\/media?parent=12802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}